{"id":6045,"date":"2026-05-12T16:25:36","date_gmt":"2026-05-12T16:25:36","guid":{"rendered":"https:\/\/colchonesyhogarcordoba.com\/?post_type=product&#038;p=6045"},"modified":"2026-05-12T16:59:27","modified_gmt":"2026-05-12T16:59:27","slug":"hot-sale-super-combo-de-2-plazas-y-media","status":"publish","type":"product","link":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/","title":{"rendered":"HOT SALE: S\u00faper Combo Resortes de 2 plazas"},"content":{"rendered":"<p>S\u00faper Combo de 2 plazas con colch\u00f3n de resortes que soporta hasta 90 kg por plaza.<\/p>\n<p>Incluye: Base + almohadas + sabanas + acolchado de regalo!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00faper Combo de 2 plazas con colch\u00f3n de resortes que soporta hasta 90 kg por plaza. Incluye: Base + almohadas + sabanas + acolchado de regalo! &nbsp;<\/p>\n","protected":false},"featured_media":6029,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false},"product_brand":[],"product_cat":[286,45,309,295],"product_tag":[],"class_list":{"0":"post-6045","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-conjuntos-somier","7":"product_cat-conjuntos-sommier-dos-plazas","8":"product_cat-hot-sale","9":"product_cat-ofertas-especiales","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HOT SALE: S\u00faper Combo Resortes de 2 plazas -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HOT SALE: S\u00faper Combo Resortes de 2 plazas -\" \/>\n<meta property=\"og:description\" content=\"S\u00faper Combo de 2 plazas con colch\u00f3n de resortes que soporta hasta 90 kg por plaza. Incluye: Base + almohadas + sabanas + acolchado de regalo! &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:59:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/\",\"name\":\"HOT SALE: S\u00faper Combo Resortes de 2 plazas -\",\"isPartOf\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg\",\"datePublished\":\"2026-05-12T16:25:36+00:00\",\"dateModified\":\"2026-05-12T16:59:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg\",\"contentUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/colchonesyhogarcordoba.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TIENDA\",\"item\":\"https:\/\/colchonesyhogarcordoba.com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HOT SALE: S\u00faper Combo Resortes de 2 plazas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#website\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"name\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/colchonesyhogarcordoba.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#organization\",\"name\":\"Colchones y Hogar C\u00f3rdoba\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png\",\"contentUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png\",\"width\":1026,\"height\":1026,\"caption\":\"Colchones y Hogar C\u00f3rdoba\"},\"image\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/\",\"https:\/\/www.facebook.com\/ColchonesyhogarCordobaOficial\",\"https:\/\/www.tiktok.com\/@colchonesyhogarcordoba\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HOT SALE: S\u00faper Combo Resortes de 2 plazas -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/","og_locale":"es_ES","og_type":"article","og_title":"HOT SALE: S\u00faper Combo Resortes de 2 plazas -","og_description":"S\u00faper Combo de 2 plazas con colch\u00f3n de resortes que soporta hasta 90 kg por plaza. Incluye: Base + almohadas + sabanas + acolchado de regalo! &nbsp;","og_url":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/","article_publisher":"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/","article_modified_time":"2026-05-12T16:59:27+00:00","og_image":[{"width":1080,"height":1350,"url":"http:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/","url":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/","name":"HOT SALE: S\u00faper Combo Resortes de 2 plazas -","isPartOf":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage"},"image":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage"},"thumbnailUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg","datePublished":"2026-05-12T16:25:36+00:00","dateModified":"2026-05-12T16:59:27+00:00","breadcrumb":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#primaryimage","url":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg","contentUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/H3.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/hot-sale-super-combo-de-2-plazas-y-media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/colchonesyhogarcordoba.com\/"},{"@type":"ListItem","position":2,"name":"TIENDA","item":"https:\/\/colchonesyhogarcordoba.com\/"},{"@type":"ListItem","position":3,"name":"HOT SALE: S\u00faper Combo Resortes de 2 plazas"}]},{"@type":"WebSite","@id":"https:\/\/colchonesyhogarcordoba.com\/#website","url":"https:\/\/colchonesyhogarcordoba.com\/","name":"https:\/\/colchonesyhogarcordoba.com\/","description":"","publisher":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colchonesyhogarcordoba.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/colchonesyhogarcordoba.com\/#organization","name":"Colchones y Hogar C\u00f3rdoba","url":"https:\/\/colchonesyhogarcordoba.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/","url":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png","contentUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png","width":1026,"height":1026,"caption":"Colchones y Hogar C\u00f3rdoba"},"image":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/","https:\/\/www.facebook.com\/ColchonesyhogarCordobaOficial","https:\/\/www.tiktok.com\/@colchonesyhogarcordoba"]}]}},"_links":{"self":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/6045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=6045"}],"version-history":[{"count":3,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/6045\/revisions"}],"predecessor-version":[{"id":6050,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/6045\/revisions\/6050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/media\/6029"}],"wp:attachment":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=6045"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=6045"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=6045"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=6045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}