{"id":4088,"date":"2024-10-10T15:35:40","date_gmt":"2024-10-10T15:35:40","guid":{"rendered":"https:\/\/colchonesyhogarcordoba.com\/?post_type=product&#038;p=4088"},"modified":"2026-05-12T16:02:15","modified_gmt":"2026-05-12T16:02:15","slug":"respaldo-willam-o-ecocuero-capitone-clasico-200","status":"publish","type":"product","link":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/","title":{"rendered":"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200"},"content":{"rendered":"<p>RESPALDO 2.00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RESPALDO 2.00<\/p>\n","protected":false},"featured_media":5999,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false},"product_brand":[],"product_cat":[253],"product_tag":[],"class_list":{"0":"post-4088","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-respaldos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -\" \/>\n<meta property=\"og:description\" content=\"RESPALDO 2.00\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:02:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/70-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/\",\"name\":\"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -\",\"isPartOf\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png\",\"datePublished\":\"2024-10-10T15:35:40+00:00\",\"dateModified\":\"2026-05-12T16:02:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png\",\"contentUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/colchonesyhogarcordoba.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TIENDA\",\"item\":\"https:\/\/colchonesyhogarcordoba.com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#website\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"name\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/colchonesyhogarcordoba.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#organization\",\"name\":\"Colchones y Hogar C\u00f3rdoba\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png\",\"contentUrl\":\"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png\",\"width\":1026,\"height\":1026,\"caption\":\"Colchones y Hogar C\u00f3rdoba\"},\"image\":{\"@id\":\"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/\",\"https:\/\/www.facebook.com\/ColchonesyhogarCordobaOficial\",\"https:\/\/www.tiktok.com\/@colchonesyhogarcordoba\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/","og_locale":"es_ES","og_type":"article","og_title":"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -","og_description":"RESPALDO 2.00","og_url":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/","article_publisher":"https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/","article_modified_time":"2026-05-12T16:02:15+00:00","og_image":[{"width":1080,"height":1080,"url":"http:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/70-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/","url":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/","name":"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200 -","isPartOf":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage"},"image":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage"},"thumbnailUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png","datePublished":"2024-10-10T15:35:40+00:00","dateModified":"2026-05-12T16:02:15+00:00","breadcrumb":{"@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#primaryimage","url":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png","contentUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2026\/05\/74.png","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/colchonesyhogarcordoba.com\/index.php\/product\/respaldo-willam-o-ecocuero-capitone-clasico-200\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/colchonesyhogarcordoba.com\/"},{"@type":"ListItem","position":2,"name":"TIENDA","item":"https:\/\/colchonesyhogarcordoba.com\/"},{"@type":"ListItem","position":3,"name":"RESPALDO WILLIAM o ECOCUERO CAPITONE CLASICO 200"}]},{"@type":"WebSite","@id":"https:\/\/colchonesyhogarcordoba.com\/#website","url":"https:\/\/colchonesyhogarcordoba.com\/","name":"https:\/\/colchonesyhogarcordoba.com\/","description":"","publisher":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colchonesyhogarcordoba.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/colchonesyhogarcordoba.com\/#organization","name":"Colchones y Hogar C\u00f3rdoba","url":"https:\/\/colchonesyhogarcordoba.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/","url":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png","contentUrl":"https:\/\/colchonesyhogarcordoba.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-15.50.48-fotor-202410240540.png","width":1026,"height":1026,"caption":"Colchones y Hogar C\u00f3rdoba"},"image":{"@id":"https:\/\/colchonesyhogarcordoba.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/colchonesyhogarcordobaoficial\/","https:\/\/www.facebook.com\/ColchonesyhogarCordobaOficial","https:\/\/www.tiktok.com\/@colchonesyhogarcordoba"]}]}},"_links":{"self":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/4088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=4088"}],"version-history":[{"count":2,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/4088\/revisions"}],"predecessor-version":[{"id":4439,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product\/4088\/revisions\/4439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/media\/5999"}],"wp:attachment":[{"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=4088"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=4088"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=4088"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/colchonesyhogarcordoba.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=4088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}